{"id":53530,"date":"2022-01-21T16:17:30","date_gmt":"2022-01-21T19:17:30","guid":{"rendered":"https:\/\/bodegaoutdoor.cl\/store\/product\/chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre-abrigo-de-camping-escalada-trekking-rompevientos-de-viaje-negro-otono\/"},"modified":"2026-08-22T06:19:25","modified_gmt":"2026-08-22T10:19:25","slug":"chaqueta-impermeable-para-hombre-y-mujer-deportes-outdoor-trekking","status":"publish","type":"product","link":"https:\/\/bodegaoutdoor.cl\/store\/product\/chaqueta-impermeable-para-hombre-y-mujer-deportes-outdoor-trekking\/","title":{"rendered":"Chaqueta impermeable para hombre y mujer, deportes outdoor,  Trekking"},"content":{"rendered":"<p style=\"text-align: center;\"><video style=\"max-width: 100%;\" src=\"\/\/cloud.video.taobao.com\/play\/u\/2962252907\/p\/1\/e\/6\/t\/10301\/284424663004.mp4\" poster=\"https:\/\/ae01.alicdn.com\/kf\/Hdab8db98f4154bd283ab7f33583197a99\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg,https:\/\/ae01.alicdn.com\/kf\/Ha3e133b8b620408993849221ac57474dc\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg,https:\/\/ae01.alicdn.com\/kf\/H990bc89353e546fbae908df2bde96914o\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg,https:\/\/ae01.alicdn.com\/kf\/H64f8fe1f9b914ef6a22498f81f9308c51\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg,https:\/\/ae01.alicdn.com\/kf\/Hbf3b35da211546dfb039f9a3d0ecd5deE\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg,https:\/\/ae01.alicdn.com\/kf\/H0de9e0b7050547ad829bfba05d39458ae\/Chaqueta-de-lluvia-impermeable-para-hombre-y-mujer-chaquetas-de-senderismo-para-deportes-al-aire-libre.jpg\" preload=\"auto\" controls=\"controls\" width=\"100%\" height=\"100%\"><\/video><\/p>\n<p><span style=\"font-size: 36px;\">Talla de hombre<\/span><\/p>\n<table style=\"width: 89.9088%;\" border=\"1\" cellspacing=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\"><strong>Talla grande<\/strong><\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\"><strong>Talla de EE. UU.<\/strong><\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\"><strong>Tama\u00f1o RU<\/strong><\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\"><strong>Longitud superior<\/strong><\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\"><strong>Cors\u00e9 de busto<\/strong><\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\"><strong>Bolso de hombro<\/strong><\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\"><strong>Manga larga<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">L<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">Modelo XS<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">43<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">67cm<\/p>\n<p style=\"text-align: center;\">(26,4 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">109cm<\/p>\n<p style=\"text-align: center;\">(42,9 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">43cm<\/p>\n<p style=\"text-align: center;\">(16,9 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">57,5 cm<\/p>\n<p style=\"text-align: center;\">(22,6 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">Modelo XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">S<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">46<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">69cm<\/p>\n<p style=\"text-align: center;\">(27,2 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">113cm<\/p>\n<p style=\"text-align: center;\">(44,5 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">46cm<\/p>\n<p style=\"text-align: center;\">(18,1 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">59cm<\/p>\n<p style=\"text-align: center;\">(23,2 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">2XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">M<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">48<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">71cm<\/p>\n<p style=\"text-align: center;\">(28 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">117cm<\/p>\n<p style=\"text-align: center;\">(46,1 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">47,5 cm<\/p>\n<p style=\"text-align: center;\">(18,7 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">60,5 cm<\/p>\n<p style=\"text-align: center;\">(23,8 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">Modelo 3XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">L<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">49<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">73cm<\/p>\n<p style=\"text-align: center;\">(28,7 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">121cm<\/p>\n<p style=\"text-align: center;\">(47,6 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">49cm<\/p>\n<p style=\"text-align: center;\">(19,3 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">62cm<\/p>\n<p style=\"text-align: center;\">(24,4 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">Modelo 4XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">Modelo XL<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">51<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">75cm<\/p>\n<p style=\"text-align: center;\">(29,5 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">125cm<\/p>\n<p style=\"text-align: center;\">(49,2 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">50,5 cm<\/p>\n<p style=\"text-align: center;\">(19,9 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">63,5 cm<\/p>\n<p style=\"text-align: center;\">(25 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">Modelo 5XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">2XL<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">52<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">77cm<\/p>\n<p style=\"text-align: center;\">(30,3 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">129cm<\/p>\n<p style=\"text-align: center;\">(50,8 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">52cm<\/p>\n<p style=\"text-align: center;\">(20,5 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">65cm<\/p>\n<p style=\"text-align: center;\">(25,6 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 11.6386%;\">\n<p style=\"text-align: center;\">Modelo 6XL<\/p>\n<\/td>\n<td style=\"width: 13.9357%;\">\n<p style=\"text-align: center;\">Modelo 3XL<\/p>\n<\/td>\n<td style=\"width: 14.3951%;\">\n<p style=\"text-align: center;\">53.<\/p>\n<\/td>\n<td style=\"width: 14.5482%;\">\n<p style=\"text-align: center;\">79cm<\/p>\n<p style=\"text-align: center;\">(33,1 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.4671%;\">\n<p style=\"text-align: center;\">131cm<\/p>\n<p style=\"text-align: center;\">(51,5 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 15.3139%;\">\n<p style=\"text-align: center;\">53cm<\/p>\n<p style=\"text-align: center;\">(20,8 pulgadas)<\/p>\n<\/td>\n<td style=\"width: 28.4143%;\">\n<p style=\"text-align: center;\">66,5 cm<\/p>\n<p style=\"text-align: center;\">(26,1 pulgadas)<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"clear: both; text-align: center;\">\n<p><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-wstabi.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 36px;\">Talla de mujer<\/span><\/p>\n<table style=\"width: 655px;\" border=\"1\" cellspacing=\"0\" align=\"center\">\n<tbody>\n<tr>\n<td style=\"width: 75px;\"><strong>Talla grande<\/strong><\/td>\n<td style=\"width: 95px;\"><strong>Talla de EE. UU.<\/strong><\/td>\n<td style=\"width: 95px;\"><strong>Tama\u00f1o RU<\/strong><\/td>\n<td style=\"width: 95px;\"><strong>Longitud superior<\/strong><\/td>\n<td style=\"width: 103px;\"><strong>Cors\u00e9 de busto<\/strong><\/td>\n<td style=\"width: 102px;\"><strong>Bolso de hombro<\/strong><\/td>\n<td style=\"width: 95px;\"><strong>Manga larga<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">M<\/td>\n<td style=\"width: 95px;\">Modelo XXS<\/td>\n<td style=\"width: 95px;\">43<\/td>\n<td style=\"width: 95px;\">62cm<\/p>\n<p>(24 pulgadas)<\/td>\n<td style=\"width: 103px;\">98cm<\/p>\n<p>(38 pulgadas)<\/td>\n<td style=\"width: 102px;\">42cm<\/p>\n<p>(16,5 pulgadas)<\/td>\n<td style=\"width: 95px;\">55cm<\/p>\n<p>(21,6 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">L<\/td>\n<td style=\"width: 95px;\">Modelo XS<\/td>\n<td style=\"width: 95px;\">46<\/td>\n<td style=\"width: 95px;\">64cm<\/p>\n<p>(25 pulgadas)<\/td>\n<td style=\"width: 103px;\">102cm<\/p>\n<p>(40 pulgadas)<\/td>\n<td style=\"width: 102px;\">44cm<\/p>\n<p>(17,3 pulgadas)<\/td>\n<td style=\"width: 95px;\">57cm<\/p>\n<p>(22,4 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">Modelo XL<\/td>\n<td style=\"width: 95px;\">S<\/td>\n<td style=\"width: 95px;\">48<\/td>\n<td style=\"width: 95px;\">67cm<\/p>\n<p>(26 pulgadas)<\/td>\n<td style=\"width: 103px;\">106cm<\/p>\n<p>(41,7 pulgadas)<\/td>\n<td style=\"width: 102px;\">45cm<\/p>\n<p>(17,7 pulgadas)<\/td>\n<td style=\"width: 95px;\">59cm<\/p>\n<p>(23,2 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">2XL<\/td>\n<td style=\"width: 95px;\">M<\/td>\n<td style=\"width: 95px;\">49<\/td>\n<td style=\"width: 95px;\">69cm<\/p>\n<p>(27 pulgadas)<\/td>\n<td style=\"width: 103px;\">108cm<\/p>\n<p>(42,5 pulgadas)<\/td>\n<td style=\"width: 102px;\">47cm<\/p>\n<p>(18,5 pulgadas)<\/td>\n<td style=\"width: 95px;\">61cm<\/p>\n<p>(24 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">Modelo 3XL<\/td>\n<td style=\"width: 95px;\">L<\/td>\n<td style=\"width: 95px;\">51<\/td>\n<td style=\"width: 95px;\">72cm<\/p>\n<p>(28 pulgadas)<\/td>\n<td style=\"width: 103px;\">112cm<\/p>\n<p>(44 pulgadas)<\/td>\n<td style=\"width: 102px;\">48cm<\/p>\n<p>(18,9 pulgadas)<\/td>\n<td style=\"width: 95px;\">63cm<\/p>\n<p>(24,8 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\">Modelo 4XL<\/td>\n<td style=\"width: 95px;\">Modelo XL<\/td>\n<td style=\"width: 95px;\">52<\/td>\n<td style=\"width: 95px;\">74cm<\/p>\n<p>(29 pulgadas)<\/td>\n<td style=\"width: 103px;\">116cm<\/p>\n<p>(45,6 pulgadas)<\/td>\n<td style=\"width: 102px;\">50cm<\/p>\n<p>(19,6 pulgadas)<\/td>\n<td style=\"width: 95px;\">65cm<\/p>\n<p>(25,5 pulgadas)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 75px;\"><\/td>\n<td style=\"width: 95px;\"><\/td>\n<td style=\"width: 95px;\"><\/td>\n<td style=\"width: 95px;\"><\/td>\n<td style=\"width: 103px;\"><\/td>\n<td style=\"width: 102px;\"><\/td>\n<td style=\"width: 95px;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-c9znvt.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-cupaec.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/p>\n<p><span style=\"font-size: 28px;\">Chaqueta de senderismo abrigada<\/span><\/p>\n<p><span style=\"font-size: 28px;\"><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-bx8fq3.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-mx5rh0.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/span><\/p>\n<p><span style=\"font-size: 28px;\">A prueba de agua<\/span><\/p>\n<p><span style=\"font-size: 28px;\"><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-dn4eis.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/span><\/p>\n<p><span style=\"font-size: 28px;\">Sombrero desmontable<\/span><\/p>\n<p><span style=\"font-size: 28px;\"><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-uj4rvq.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/span><\/p>\n<p><span style=\"font-size: 28px;\">Transpirable, transpirable<\/span><\/p>\n<p><span style=\"font-size: 28px;\"><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-rpg3ft.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/span><\/p>\n<p><span style=\"font-size: 28px;\"><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-ibmdxu.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-adznqg.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-sqo3g1.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-tmujqd.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-t41fnj.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-izrzkh.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-w2nt4i.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><img decoding=\"async\" title=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" src=\"https:\/\/bodegaoutdoor.cl\/store\/wp-content\/uploads\/2022\/01\/53530-bwyruv.jpg\" alt=\"Chaqueta de lluvia impermeable para hombre y mujer, chaquetas de senderismo para deportes al aire libre, abrigo de Camping, escalada, Trekking, rompevientos de viaje, negro, oto\u00f1o\" \/><\/span><\/p>\n<\/div>\n<div><\/div>\n\n    <div class=\"xs_social_share_widget xs_share_url after_content \t\tmain_content  wslu-style-1 wslu-share-box-shaped wslu-fill-colored wslu-none wslu-share-horizontal wslu-theme-font-no wslu-main_content\">\n\n\t\t\n        <ul>\n\t\t\t        <\/ul>\n    <\/div> \n","protected":false},"excerpt":{"rendered":"<p>Talla de hombre Talla grande Talla de EE. UU. Tama\u00f1o RU Longitud superior Cors\u00e9 de busto Bolso de hombro Manga larga L Modelo XS 43 67cm (26,4 pulgadas) 109cm (42,9 pulgadas) 43cm (16,9 pulgadas) 57,5 cm (22,6 pulgadas) Modelo XL S 46 69cm (27,2 pulgadas) 113cm (44,5 pulgadas) 46cm (18,1 pulgadas) 59cm (23,2 pulgadas) 2XL [&hellip;]<\/p>\n","protected":false},"featured_media":53611,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[73,70,62,63],"product_tag":[1483,3764,3250,1282,481],"class_list":["post-53530","product","type-product","status-publish","has-post-thumbnail","product_cat-hombre-tercera","product_cat-mujer-tercera","product_cat-vestuario-hombre","product_cat-vestuario-mujer","product_tag-chaqueta","product_tag-corta-viento","product_tag-cortaviento","product_tag-impermeable","product_tag-outdoor","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product\/53530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/comments?post=53530"}],"version-history":[{"count":3,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product\/53530\/revisions"}],"predecessor-version":[{"id":59978,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product\/53530\/revisions\/59978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/media\/53611"}],"wp:attachment":[{"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/media?parent=53530"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product_brand?post=53530"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product_cat?post=53530"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bodegaoutdoor.cl\/store\/wp-json\/wp\/v2\/product_tag?post=53530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}